{"id":216,"date":"2018-11-14T18:13:12","date_gmt":"2018-11-14T18:13:12","guid":{"rendered":"http:\/\/paginas.facmed.unam.mx\/deptos\/ana\/?page_id=216"},"modified":"2026-08-31T02:42:08","modified_gmt":"2026-08-31T02:42:08","slug":"alumnos","status":"publish","type":"page","link":"https:\/\/anatomia.facmed.unam.mx\/index.php\/alumnos\/","title":{"rendered":"Alumnos"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb background_enable_image=\u00bboff\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb2px|3px|0px|-2px|false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb|0px|0px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_5,3_5&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/08\/flyer-de-inicio-1920-x-739-px-1280-x-600-px.png\u00bb min_height=\u00bb474.4px\u00bb max_height=\u00bb1000px\u00bb custom_margin=\u00bb-16px||||false|false\u00bb custom_padding=\u00bb5px||2px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_toggle title=\u00bbPrograma de estudios m\u00e9dico cirujano\u00bb open_toggle_text_color=\u00bb#000000&#8243; open_toggle_background_color=\u00bb#ededed\u00bb icon_color=\u00bb#000000&#8243; toggle_icon=\u00bb&#xf042;||fa||900&#8243; open_icon_color=\u00bb#D33D57&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb title_text_color=\u00bb#000000&#8243; title_level=\u00bbh6&#8243; title_font=\u00bbPoppins||||||||\u00bb title_font_size=\u00bb15px\u00bb closed_title_font=\u00bbArchivo|600|||||||\u00bb closed_title_text_align=\u00bbcenter\u00bb closed_title_font_size=\u00bb17px\u00bb body_font=\u00bbPoppins|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb border_width_all=\u00bb0px\u00bb border_color_all=\u00bb#000000&#8243; box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><a href=\"https:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2022\/09\/ANATOMIA-PLAN-ACTUALIZADO-2022.pdf\" target=\"_blank\" rel=\"noopener\">PLAN DE ESTUDIOS 2010<\/a><\/h4>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00bbPerfiles de referencia\u00bb open_toggle_text_color=\u00bb#D33D57&#8243; open_toggle_background_color=\u00bb#ededed\u00bb closed_toggle_text_color=\u00bb#000000&#8243; icon_color=\u00bb#000000&#8243; toggle_icon=\u00bb&#x47;||divi||400&#8243; open_icon_color=\u00bb#D33D57&#8243; admin_label=\u00bbConmutador\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb title_text_color=\u00bb#D33D57&#8243; title_font=\u00bbPoppins||||||||\u00bb title_font_size=\u00bb15px\u00bb closed_title_font=\u00bbArchivo|600|||||||\u00bb closed_title_text_align=\u00bbcenter\u00bb closed_title_font_size=\u00bb17px\u00bb body_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||0px||false|false\u00bb link_option_url_new_window=\u00bbon\u00bb border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/Perfil-de-referencia-Anatomia-Bloque-1-2027-0.pdf\" target=\"_blank\" rel=\"noopener\">PERFIL DE REFERENCIA BLOQUE 1<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00bbEstructuras a identificar\u00bb open_toggle_text_color=\u00bb#000000&#8243; open_toggle_background_color=\u00bb#ededed\u00bb icon_color=\u00bb#000000&#8243; toggle_icon=\u00bb&#x47;||divi||400&#8243; open_icon_color=\u00bb#D33D57&#8243; admin_label=\u00bbConmutador\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb title_text_color=\u00bb#000000&#8243; title_font=\u00bbPoppins||||||||\u00bb title_font_size=\u00bb15px\u00bb closed_title_font=\u00bbArchivo|600|||||||\u00bb closed_title_text_align=\u00bbcenter\u00bb closed_title_font_size=\u00bb17px\u00bb body_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||0px||false|false\u00bb border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/Lista-de-estructuras-a-identificar-Anatomia-Bloque-1-2027-0.pdf\" target=\"_blank\" rel=\"noopener\">ESTRUCTURAS A IDENTIFICAR BLOQUE 1<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00bbBibliograf\u00eda b\u00e1sica \u00bb open_toggle_text_color=\u00bb#000000&#8243; open_toggle_background_color=\u00bb#ededed\u00bb closed_toggle_text_color=\u00bb#000000&#8243; icon_color=\u00bb#000000&#8243; toggle_icon=\u00bb&#x47;||divi||400&#8243; open_icon_color=\u00bb#000000&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb title_text_color=\u00bb#000000&#8243; title_font=\u00bbPoppins||||||||\u00bb title_font_size=\u00bb15px\u00bb closed_title_font=\u00bbArchivo||||||||\u00bb closed_title_text_align=\u00bbcenter\u00bb closed_title_font_size=\u00bb17px\u00bb body_font=\u00bbPoppins|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||0px||false|false\u00bb border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/Bibliografia-Anatomia-2027-0-Final-1.pdf\" target=\"_blank\" rel=\"noopener\">Bibliograf\u00eda B\u00e1sica<\/a><\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00bbHorario por Grupo\u00bb open_toggle_text_color=\u00bb#000000&#8243; icon_color=\u00bb#000000&#8243; toggle_icon=\u00bb&#x47;||divi||400&#8243; open_icon_color=\u00bb#000000&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb title_text_color=\u00bb#000000&#8243; title_font=\u00bbPoppins||||||||\u00bb title_font_size=\u00bb15px\u00bb closed_title_font=\u00bbArchivo|600|||||||\u00bb closed_title_text_align=\u00bbcenter\u00bb closed_title_font_size=\u00bb17px\u00bb body_font=\u00bbPoppins||||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||0px||false|false\u00bb hover_enabled=\u00bb0&#8243; border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><a href=\"https:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/20260828203706-horarios-primer-ano-2027-0.pdf\">DISTRIBUCI\u00d3N DE HORARIOS POR GRUPOS PRIMER A\u00d1O<\/a><\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00bbCalendario Acad\u00e9mico y de Ex\u00e1menes\u00bb open_toggle_text_color=\u00bb#D33D57&#8243; icon_color=\u00bb#000000&#8243; toggle_icon=\u00bb&#x47;||divi||400&#8243; open_icon_color=\u00bb#000000&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb title_text_color=\u00bb#000000&#8243; title_font=\u00bbPoppins||||||||\u00bb title_font_size=\u00bb15px\u00bb closed_title_font=\u00bbArchivo|600|||||||\u00bb closed_title_text_align=\u00bbcenter\u00bb closed_title_font_size=\u00bb17px\u00bb body_font=\u00bbPoppins||||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||0px||false|false\u00bb link_option_url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2023\/01\/MC_calendario_1ero.pdf\u00bb link_option_url_new_window=\u00bbon\u00bb border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/20260805145944-mc-1-1-sujeto.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000000;\">CALENDARIO ESCOLAR Y EXAMENES 2026-2027<\/span><\/a><\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00bbLineamientos de evaluaci\u00f3n 2024&#8243; open_toggle_text_color=\u00bb#000000&#8243; icon_color=\u00bb#000000&#8243; toggle_icon=\u00bb&#x47;||divi||400&#8243; open_icon_color=\u00bb#D33D57&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb title_text_color=\u00bb#000000&#8243; title_font=\u00bbPoppins||||||||\u00bb title_font_size=\u00bb15px\u00bb closed_title_font=\u00bbArchivo|600|||||||\u00bb closed_title_text_align=\u00bbcenter\u00bb closed_title_font_size=\u00bb17px\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||0px||false|false\u00bb border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2023\/07\/LINEAMIENTOS-PARA-LA-EVALUACIOiN-DEL-ALUMNADO-DE-LA-LICENCIATURA-DE-MEiDICO-CIRUJANO.pdf\" target=\"_blank\" rel=\"noopener\" title=\"Lineamientos de Evaluaci\u00f3n 2024\">Lineamientos de evaluaci\u00f3n 2024<\/a><\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00bbPr\u00e1cticas de Anatom\u00eda\u00bb open_toggle_text_color=\u00bb#000000&#8243; icon_color=\u00bb#000000&#8243; toggle_icon=\u00bb&#x47;||divi||400&#8243; open_icon_color=\u00bb#000000&#8243; module_id=\u00bbPRACTICAS\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb title_text_color=\u00bb#000000&#8243; title_font=\u00bbPoppins||||||||\u00bb title_font_size=\u00bb14px\u00bb closed_title_font=\u00bbArchivo|600|||||||\u00bb closed_title_text_align=\u00bbcenter\u00bb closed_title_font_size=\u00bb17px\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||0px||false|false\u00bb link_option_url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/index.php\/alumnos\/#practicas\u00bb custom_css_free_form=\u00bbPRACTICAS\u00bb border_width_all=\u00bb0px\u00bb box_shadow_style=\u00bbpreset6&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/anatomia.facmed.unam.mx\/index.php\/alumnos\/#practicas\">Pr\u00e1cticas de Anatom\u00eda<\/a><\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][dica_divi_carousel show_items_desktop=\u00bb2&#8243; show_items_tablet=\u00bb1&#8243; multislide=\u00bbon\u00bb transition_duration=\u00bb800&#8243; autoplay=\u00bbon\u00bb arrow_nav=\u00bbon\u00bb item_spacing=\u00bb36&#8243; advanced_effect=\u00bbcoverflow\u00bb overlay_color_field_bgcolor=\u00bbrgba(255,255,255,0.85)\u00bb social_container_padding=\u00bb-1px||||false|false\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb z_index=\u00bb1&#8243; max_width=\u00bb77%\u00bb custom_margin=\u00bb|-37px||||\u00bb hover_transition_duration=\u00bb450ms\u00bb global_colors_info=\u00bb{}\u00bb][dica_divi_carouselitem button_url_new_window=\u00bb1&#8243; image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/Concurso-de-anatomia-_page-0001.jpg\u00bb image_lightbox=\u00bbon\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb link_option_url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/Concurso-de-anatomia-_page-0001.jpg\u00bb link_option_url_new_window=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=\u00bb1&#8243; image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/FELSALUD2026_UNAM.jpg\u00bb image_lightbox=\u00bbon\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb link_option_url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/FELSALUD2026_UNAM.jpg\u00bb link_option_url_new_window=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=\u00bb1&#8243; image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/06\/jpg.jpg\u00bb image_lightbox=\u00bbon\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=\u00bb1&#8243; image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/03\/100-k.jpeg\u00bb image_lightbox=\u00bbon\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=\u00bb1&#8243; image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-13-at-8.26.53-AM.jpeg\u00bb image_lightbox=\u00bbon\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=\u00bb1&#8243; image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/08\/Flyers.pdf_page-0001.jpg\u00bb image_lightbox=\u00bbon\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=\u00bb1&#8243; image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-20-at-3.11.10-PM.jpeg\u00bb image_lightbox=\u00bbon\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=\u00bb1&#8243; image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-12-at-2.38.59-PM.jpeg\u00bb image_lightbox=\u00bbon\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/dica_divi_carouselitem][dica_divi_carouselitem button_url_new_window=\u00bb1&#8243; image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-08-26-at-12.37.19-PM.jpeg\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb link_option_url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-08-26-at-12.37.19-PM.jpeg\u00bb link_option_url_new_window=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/dica_divi_carouselitem][\/dica_divi_carousel][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#86192C\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb width=\u00bb88%\u00bb max_width=\u00bb1392px\u00bb custom_margin=\u00bb|236px|0px|335px|false|false\u00bb custom_margin_tablet=\u00bb|236px|0px|335px|false|false\u00bb custom_margin_phone=\u00bb-500px|0px||0px|false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb border_width_all=\u00bb0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text module_id=\u00bbasesorias\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbPoppins|700|||||||\u00bb text_text_color=\u00bb#E09900&#8243; text_font_size=\u00bb16px\u00bb text_letter_spacing=\u00bb2px\u00bb text_orientation=\u00bbcenter\u00bb text_text_shadow_style=\u00bbpreset2&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><span style=\"color: #ff0000;\">PROGRAMA DE ASESORAMIENTO ACAD\u00c9MICO<\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; module_id=\u00bbalumnos\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb width_tablet=\u00bb\u00bb width_phone=\u00bb68%\u00bb width_last_edited=\u00bbon|phone\u00bb custom_margin=\u00bb-429px||||false|false\u00bb custom_padding=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_countdown_timer title=\u00bb&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;PR\u00d3XIMO&#8230; &#8230;&#8230;&#8230;EXAMEN&#8230;&#8230;&#8230; PRIMER DEPARTAMENTAL\u00bb date_time=\u00bb2026-04-25 08:00&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#FFF347&#8243; header_font_size=\u00bb20px\u00bb header_letter_spacing=\u00bb5px\u00bb header_line_height=\u00bb2.1em\u00bb numbers_font=\u00bb|800|||||||\u00bb numbers_text_color=\u00bb#00a315&#8243; numbers_font_size=\u00bb32px\u00bb numbers_line_height=\u00bb11px\u00bb label_font=\u00bb|700|||||||\u00bb background_image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/03\/reloj.png\u00bb background_layout=\u00bblight\u00bb max_width=\u00bb85%\u00bb height=\u00bb318px\u00bb max_height=\u00bb423px\u00bb custom_margin=\u00bb-5px||||false|false\u00bb header_text_shadow_style=\u00bbpreset3&#8243; header_text_shadow_color=\u00bb#000000&#8243; numbers_text_shadow_style=\u00bbpreset3&#8243; numbers_text_shadow_horizontal_length=\u00bb-0.01em\u00bb numbers_text_shadow_blur_strength=\u00bb0.42em\u00bb text_shadow_style=\u00bbpreset1&#8243; text_shadow_horizontal_length=\u00bb0.08em\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_countdown_timer][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2024\/11\/photo_5021551973392035252_y.jpg\u00bb title_text=\u00bbphoto_5021551973392035252_y\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb max_height=\u00bb335px\u00bb border_radii=\u00bbon|50px|50px|50px|50px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2024\/11\/photo_5021551973392035253_y.jpg\u00bb title_text=\u00bbphoto_5021551973392035253_y\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb max_height=\u00bb335px\u00bb hover_enabled=\u00bb0&#8243; border_radii=\u00bbon|50px|50px|50px|50px\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.19.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-06-12-at-1.10.21-PM.jpeg\u00bb title_text=\u00bbWhatsApp Image 2025-06-12 at 1.10.21 PM\u00bb url=\u00bbhttps:\/\/calendar.app.google\/sVihCALNZ1sbbi6L8&#8243; url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb max_height=\u00bb335px\u00bb border_radii=\u00bbon|50px|50px|50px|50px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#86192C\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb image=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/09\/14080-1920\u00d7500.png\u00bb content_max_width=\u00bb596px\u00bb module_id=\u00bbpracticas\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#E09900&#8243; height=\u00bb119px\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb||1px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><\/h1>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/09\/Practicageneralnuevo-1.png\u00bb title_text=\u00bbPracticageneralnuevo\u00bb url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2024\/08\/Docente.pdf\u00bb url_new_window=\u00bbon\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb module_alignment=\u00bbright\u00bb border_radii=\u00bbon|40px|40px|40px|40px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/09\/Practicadescrip.png\u00bb title_text=\u00bbPracticadescrip\u00bb url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2024\/09\/MANUAL-DE-PRACTICAS-BLOQUE-2-8.pdf\u00bb url_new_window=\u00bbon\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb border_radii=\u00bbon|40px|40px|40px|40px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/09\/Practicadespestuc.png\u00bb title_text=\u00bbPracticadespestuc\u00bb url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2024\/10\/PRACTICA-ESTUCHE-DE-DISECCION-.pdf\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb border_radii=\u00bbon|40px|40px|40px|40px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; module_id=\u00bbPRACTICAS\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb link_option_url=\u00bb#PRACTICAS\u00bb custom_css_free_form=\u00bbPRACTICAS\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/09\/practicadespcora.png\u00bb title_text=\u00bbpracticadespcora\u00bb url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/04\/MANUAL-DE-PRACTICAS-PRACTICA-4.pdf\u00bb url_new_window=\u00bbon\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb custom_margin=\u00bb|||400px|false|false\u00bb custom_padding=\u00bb||||false|false\u00bb border_radii=\u00bbon|40px|40px|40px|40px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_video src=\u00bbhttps:\/\/youtu.be\/HyPa3XF9ErE\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb70%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/02\/55.png\u00bb title_text=\u00bb55&#8243; url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/02\/MANUAL-DE-PRACTICAS-BLOQUE-3.-ORIGINAL.-.pdf\u00bb url_new_window=\u00bbon\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb border_radii=\u00bbon|40px|40px|40px|40px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/02\/51.png\u00bb title_text=\u00bb51&#8243; url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/02\/PRACTICA-DE-PELVIS-.pdf\u00bb url_new_window=\u00bbon\u00bb align=\u00bbright\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb border_radii=\u00bbon|40px|40px|40px|40px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/09\/practicadespespla.png\u00bb title_text=\u00bbpracticadespespla\u00bb url=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/04\/MANUAL-DE-PRACTICAS-PRACTICA-6.pdf\u00bb url_new_window=\u00bbon\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb border_radii=\u00bbon|40px|40px|40px|40px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2025\/09\/Practicadescner.png\u00bb title_text=\u00bbPracticadescner\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb47%\u00bb border_radii=\u00bbon|40px|40px|40px|40px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PLAN DE ESTUDIOS 2010PERFIL DE REFERENCIA BLOQUE 1 &nbsp; &nbsp;ESTRUCTURAS A IDENTIFICAR BLOQUE 1 &nbsp;Bibliograf\u00eda B\u00e1sicaDISTRIBUCI\u00d3N DE HORARIOS POR GRUPOS PRIMER A\u00d1OCALENDARIO ESCOLAR Y EXAMENES 2026-2027Lineamientos de evaluaci\u00f3n 2024Pr\u00e1cticas de Anatom\u00eda<div class=\"et_pb_module dica_divi_carousel dica_divi_carousel_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dica-container  desktop_middle-inside tablet_middle-inside mobile_middle-inside\" data-props='{\"desktop\":\"2\",\"tablet\":\"1\",\"mobile\":\"1\",\"speed\":\"800\",\"arrow\":\"on\",\"dots\":\"off\",\"autoplay\":\"on\",\"autoSpeed\":\"1000\",\"loop\":\"off\",\"item_spacing\":\"36\",\"center_mode\":\"off\",\"slider_effec\":\"coverflow\",\"cover_rotate\":\"50\",\"pause_onhover\":\"off\",\"multislide\":\"on\",\"cfshadow\":\"on\",\"order\":\"0\",\"lazyload\":\"off\",\"lazybefore\":\"off\",\"scroller_effect\":\"off\",\"autowidth\":\"off\",\"item_spacing_tablet\":\"36\",\"item_spacing_phone\":\"36\",\"scroller_speed\":\"4000\",\"hashNavigation\":\"off\",\"simulatetouch\":\"off\",\"allowtouchmove\":\"off\",\"slide_row\":\"1\",\"slide_row_tablet\":\"1\",\"slide_row_phone\":\"1\",\"keyboard\":\"off\",\"mousewheel\":\"off\",\"autoplay_viewport\":\"80%\"}'>\n\t\t\t\t\t\t\t \t<div class=\"swiper-container\" >\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-wrapper\"><\/div>\t\n\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t\t<div class=\"swiper-buttton-container\"><div class=\"swiper-button-prev dica-prev-btn-0\" data-icon=\"4\"><\/div><div class=\"swiper-button-next dica-next-btn-0\" data-icon=\"5\"><\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module dica_divi_carouselitem dica_divi_carouselitem_0 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t <div class=\"dica-item empty-content image_top\" data-link=\"\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/Concurso-de-anatomia-_page-0001.jpg\u00bb\"  data-hash=\"dica_divi_carouselitem_0\">\n\t\t\t\t\t\t\t\t\t<div class=\"dica-image-container\"><span class=\"image\"><img decoding=\"async\" src=\"\u00bbhttps:\/\/anatomia.facmed.unam.mx\/wp-content\/uploads\/2026\/08\/Concurso-de-anatomia-_page-0001.jpg\u00bb\" srcset=\"\" alt=\"\" class=\"dica-item-image\" width=\"f\" height=\"u\"\/><\/span><\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","jetpack_post_was_ever_published":true,"footnotes":""},"class_list":["post-216","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PaS03c-3u","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/anatomia.facmed.unam.mx\/index.php\/wp-json\/wp\/v2\/pages\/216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anatomia.facmed.unam.mx\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anatomia.facmed.unam.mx\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anatomia.facmed.unam.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anatomia.facmed.unam.mx\/index.php\/wp-json\/wp\/v2\/comments?post=216"}],"version-history":[{"count":628,"href":"https:\/\/anatomia.facmed.unam.mx\/index.php\/wp-json\/wp\/v2\/pages\/216\/revisions"}],"predecessor-version":[{"id":10289,"href":"https:\/\/anatomia.facmed.unam.mx\/index.php\/wp-json\/wp\/v2\/pages\/216\/revisions\/10289"}],"wp:attachment":[{"href":"https:\/\/anatomia.facmed.unam.mx\/index.php\/wp-json\/wp\/v2\/media?parent=216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}